{"id":1051,"date":"2019-02-16T01:58:46","date_gmt":"2019-02-16T01:58:46","guid":{"rendered":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png"},"modified":"2019-02-16T01:58:46","modified_gmt":"2019-02-16T01:58:46","slug":"favicon","status":"inherit","type":"attachment","link":"https:\/\/tornillossanmarcos.com.mx\/inicio\/favicon\/","title":{"rendered":"favicon"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-1051","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>favicon - Tornillos y Muelles San Marcos<\/title>\n<meta name=\"description\" content=\"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"favicon - Tornillos y Muelles San Marcos\" \/>\n<meta property=\"og:description\" content=\"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\" \/>\n<meta property=\"og:site_name\" content=\"Tornillos y Muelles San Marcos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TornillosSanMarcosAgs\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"65\" \/>\n\t<meta property=\"og:image:height\" content=\"65\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\",\"url\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\",\"name\":\"favicon - Tornillos y Muelles San Marcos\",\"isPartOf\":{\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#website\"},\"datePublished\":\"2019-02-16T01:58:46+00:00\",\"dateModified\":\"2019-02-16T01:58:46+00:00\",\"description\":\"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"favicon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#website\",\"url\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/\",\"name\":\"Tornillos y Muelles San Marcos\",\"description\":\"Especialistas en Herramientas e insumos profesional MRO para la Industria\",\"publisher\":{\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#organization\",\"name\":\"Tornillos y Muelles San Marcos\",\"url\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/TornillosSanMarcosAgs\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2015\/06\/tornillos_san_marcos.png\",\"contentUrl\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2015\/06\/tornillos_san_marcos.png\",\"width\":200,\"height\":97,\"caption\":\"Tornillos y Muelles San Marcos\"},\"image\":{\"@id\":\"https:\/\/tornillossanmarcos.com.mx\/inicio\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"favicon - Tornillos y Muelles San Marcos","description":"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","og_locale":"es_MX","og_type":"article","og_title":"favicon - Tornillos y Muelles San Marcos","og_description":"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.","og_url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","og_site_name":"Tornillos y Muelles San Marcos","article_publisher":"https:\/\/www.facebook.com\/TornillosSanMarcosAgs\/","og_image":[{"width":65,"height":65,"url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","type":"image\/png"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","name":"favicon - Tornillos y Muelles San Marcos","isPartOf":{"@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#website"},"datePublished":"2019-02-16T01:58:46+00:00","dateModified":"2019-02-16T01:58:46+00:00","description":"L\u00edderes en Torniller\u00eda, fijaci\u00f3n y herramientas mec\u00e1nica y el\u00e9ctricas, ahora puedes comprar en l\u00ednea para toda la Rep\u00fablica.","breadcrumb":{"@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tornillossanmarcos.com.mx\/inicio\/"},{"@type":"ListItem","position":2,"name":"favicon"}]},{"@type":"WebSite","@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#website","url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/","name":"Tornillos y Muelles San Marcos","description":"Especialistas en Herramientas e insumos profesional MRO para la Industria","publisher":{"@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tornillossanmarcos.com.mx\/inicio\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#organization","name":"Tornillos y Muelles San Marcos","url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/","sameAs":["https:\/\/www.facebook.com\/TornillosSanMarcosAgs\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2015\/06\/tornillos_san_marcos.png","contentUrl":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2015\/06\/tornillos_san_marcos.png","width":200,"height":97,"caption":"Tornillos y Muelles San Marcos"},"image":{"@id":"https:\/\/tornillossanmarcos.com.mx\/inicio\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png'><img decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":65,"height":65,"file":"2019\/02\/favicon.png","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-content\/uploads\/2019\/02\/favicon.png","_links":{"self":[{"href":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-json\/wp\/v2\/media\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tornillossanmarcos.com.mx\/inicio\/wp-json\/wp\/v2\/comments?post=1051"}]}}